{"id":1877,"date":"2022-09-13T13:35:38","date_gmt":"2022-09-13T13:35:38","guid":{"rendered":"http:\/\/elangrill.com\/?post_type=product&#038;p=1877"},"modified":"2025-10-27T09:41:49","modified_gmt":"2025-10-27T09:41:49","slug":"kebab-gyros-mod-ghi-v1","status":"publish","type":"product","link":"https:\/\/www.elangrill.com\/en\/product\/kebab-gyros-mod-ghi-v1\/","title":{"rendered":"Kebab Gyros Mod. Ghi V1"},"content":{"rendered":"<p><span style=\"text-decoration: underline;\"><strong>TECHNICAL FEATURES:<\/strong><\/span><\/p>\n<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-4 vc_hidden-xs\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<ul>\n<li>6 Resistences<\/li>\n<li>Power: 6 kW<\/li>\n<li>Voltage: V. 400 3N<\/li>\n<li>Dimensions: mm 453 x 580 x 768 h<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Scopri il piacere della preparazione del kebab con il Gyros elettrico Elangrill. Progettata per soddisfare le esigenze dei professionisti della ristorazione, questa griglia offre un modo semplice per creare kebab succulenti e gustosi. La nostra griglia per kebab assicura una distribuzione uniforme del calore per una cottura perfetta ogni volta. La sua costruzione robusta e di alta qualit\u00e0 garantisce una durata nel tempo.<\/p>","protected":false},"excerpt":{"rendered":"<p style=\"text-align: center;\">GAS OR ELECTRIC KEBAB GYROS:<br \/>\nGUARANTEED PERFECT RESULTS<\/p>","protected":false},"featured_media":3581,"template":"","meta":[],"product_brand":[],"product_cat":[93],"product_tag":[],"class_list":{"0":"post-1877","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-kebab-modelli-elettrici","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.elangrill.com\/en\/wp-json\/wp\/v2\/product\/1877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elangrill.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.elangrill.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elangrill.com\/en\/wp-json\/wp\/v2\/media\/3581"}],"wp:attachment":[{"href":"https:\/\/www.elangrill.com\/en\/wp-json\/wp\/v2\/media?parent=1877"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.elangrill.com\/en\/wp-json\/wp\/v2\/product_brand?post=1877"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.elangrill.com\/en\/wp-json\/wp\/v2\/product_cat?post=1877"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.elangrill.com\/en\/wp-json\/wp\/v2\/product_tag?post=1877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}