{"id":1032,"date":"2022-08-24T13:04:31","date_gmt":"2022-08-24T13:04:31","guid":{"rendered":"http:\/\/elangrill.com\/?post_type=product&#038;p=1032"},"modified":"2025-10-27T09:38:01","modified_gmt":"2025-10-27T09:38:01","slug":"delta-108p","status":"publish","type":"product","link":"https:\/\/www.elangrill.com\/en\/product\/delta-108p\/","title":{"rendered":"Delta 108P"},"content":{"rendered":"<p><span style=\"text-decoration: underline;\"><strong>TECHNICAL FEATURES:<\/strong><\/span><\/p>\n<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-4 vc_hidden-xs\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<ul>\n<li>Stainless steel ribbed and reinforced bearing structure<\/li>\n<li>Patented cooking system with stainless steel reflectors and reflecting bars<\/li>\n<li>Interior lighting<\/li>\n<li>Removable stainless steel bucket<\/li>\n<li>Grill Plus Motors<\/li>\n<li>Thermostatic safety valve<\/li>\n<li>Temperature indicator<\/li>\n<li>Retractable glass<\/li>\n<li>Illuminated front panel<\/li>\n<li>New rounded line<\/li>\n<li>Stainless steel discs<\/li>\n<li>12 + 6 stainless steel tubular spits 12 x 12 mm, 910 mm<\/li>\n<li>Dimensions: 1250 x 1040 x 980 h mm<\/li>\n<li>Weight: 190 kg<\/li>\n<li>Chicken capacity: up to 108 pieces of 1 kg<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Con la loro robustezza, i girarrosti planetari Elangrill nascono per usi intensivi, per tutte le attivit\u00e0 che devono sfornare rapidamente polli, arrosti, patatine e tanto altro. Questi modelli sono dotati del sistema Grill Plus, infatti, \u00e8 possibile bloccare i dischi e far ruotare le sole aste cos\u00ec da cuocere pi\u00f9 rapidamente determinati prodotti con un considerevole risparmio energetico. Il suo vetro frontale non solo permette di ammirare il cibo al suo interno, ma consente anche di mantenere una visione chiara del processo di cottura, offrendo un coinvolgimento visivo senza pari.<\/p>","protected":false},"excerpt":{"rendered":"<p style=\"text-align: center;\">THE GAS ROTISSERIE WITH SLIDING GLASS<br \/>\nFOR A MORE MODERN DESIGN<\/p>","protected":false},"featured_media":2011,"template":"","meta":[],"product_brand":[],"product_cat":[37],"product_tag":[],"class_list":{"0":"post-1032","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-planetari-delta","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.elangrill.com\/en\/wp-json\/wp\/v2\/product\/1032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elangrill.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.elangrill.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elangrill.com\/en\/wp-json\/wp\/v2\/media\/2011"}],"wp:attachment":[{"href":"https:\/\/www.elangrill.com\/en\/wp-json\/wp\/v2\/media?parent=1032"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.elangrill.com\/en\/wp-json\/wp\/v2\/product_brand?post=1032"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.elangrill.com\/en\/wp-json\/wp\/v2\/product_cat?post=1032"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.elangrill.com\/en\/wp-json\/wp\/v2\/product_tag?post=1032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}